{"id":5747,"date":"2015-07-07T23:48:17","date_gmt":"2015-07-07T23:48:17","guid":{"rendered":"http:\/\/kasperskydaily.com\/mexico\/?p=5747"},"modified":"2019-11-22T03:05:55","modified_gmt":"2019-11-22T09:05:55","slug":"watching-through-walls","status":"publish","type":"post","link":"https:\/\/latam.kaspersky.com\/blog\/watching-through-walls\/5747\/","title":{"rendered":"Mi hogar ya no es mi castillo: tecnolog\u00edas que permiten ver a trav\u00e9s de las paredes"},"content":{"rendered":"<p>A principios de 2015, el <a href=\"http:\/\/www.usatoday.com\/story\/news\/2015\/01\/19\/police-radar-see-through-walls\/22007615\/\" target=\"_blank\" rel=\"noopener nofollow\">peri\u00f3dico USA Today inici\u00f3<\/a> una serie de publicaciones sobre un radar port\u00e1til llamado <a href=\"http:\/\/www.range-r.com\/\" target=\"_blank\" rel=\"noopener nofollow\">RANGE-R<\/a>, que hab\u00eda sido utilizado por la polic\u00eda de EE.UU. y otros servicios gubernamentales. El sistema del radar permite \u201cver a trav\u00e9s de las paredes\u201d. Para ser m\u00e1s exactos, registra el movimiento que se produce dentro de espacios cerrados. La alta sensibilidad del sistema de este radar permite detectar la respiraci\u00f3n de una persona escondida en cualquier lugar del interior de un edificio o detr\u00e1s de varias paredes.<\/p>\n<p>La existencia de este dispositivo result\u00f3 sorprender a varios periodistas, quienes estaban enumerando las funciones de RANGE-R. Estos radares <a href=\"https:\/\/www.ncjrs.gov\/pdffiles1\/nij\/grants\/245944.pdf\" target=\"_blank\" rel=\"noopener nofollow\">se fabrican en<\/a> grandes cantidades desde hace mucho tiempo para cubrir las necesidades militares y de los servicios de inteligencia. Los sistemas de estos radares han sido utilizados para el rescate de rehenes en misiones del FBI, en operaciones de b\u00fasqueda y rescate de incendios, en operaciones de captura de fugitivos del\u00a0servicio del Cuerpo de Alguaciles de Estados Unidos, etc.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">FBI and US Marshals stock up on radars that can see through walls <a href=\"http:\/\/t.co\/zqDtplZnO4\" target=\"_blank\" rel=\"noopener nofollow\">http:\/\/t.co\/zqDtplZnO4<\/a> <a href=\"http:\/\/t.co\/HY3J2yJDO0\" target=\"_blank\" rel=\"noopener nofollow\">pic.twitter.com\/HY3J2yJDO0<\/a><\/p>\n<p>\u2014 Engadget (@engadget) <a href=\"https:\/\/twitter.com\/engadget\/status\/558694919435739137?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener nofollow\">January 23, 2015<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>Anteriormente, esta tecnolog\u00eda s\u00f3lo estaba disponible para algunos servicios gubernamentales. Hoy en d\u00eda, la situaci\u00f3n ha cambiado debido a los avances tecnol\u00f3gicos y la disminuci\u00f3n de costos de \u00e9stos. El sistema del radar RANGE-R tiene un costo de alrededor de 6.000 d\u00f3lares, mientras tanto siguen creando prototipos para nuevos sistemas de radar accesibles con m\u00f3dulos Wi-Fi de bajo costo.<\/p>\n<p>Por lo tanto, no ser\u00eda una sorpresa si los criminales empezaran a utilizar el mismo equipo el d\u00eda de ma\u00f1ana, as\u00ed que es el momento perfecto para examinar esta tecnolog\u00eda y sus caracter\u00edsticas.<\/p>\n<p><strong>\u00bfHay alguien con vida por ah\u00ed?<\/strong><\/p>\n<p>La tecnolog\u00eda de sensores del RANGE-R fue nombrada como; <em>Through-the-Wall Sensors (TTWS)<\/em> (\u201cSensores que atraviesan paredes\u201d, en espa\u00f1ol). Al igual que en otros radares, los sensores \u201ciluminan\u201d el campo de visi\u00f3n con ondas de radio y despu\u00e9s registran la radiaci\u00f3n reflejada.<\/p>\n<p>En teor\u00eda es algo f\u00e1cil de hacer. En la pr\u00e1ctica, los creadores de los TTWS tienen que combinar varias tecnolog\u00edas y m\u00e9todos avanzados de procesamiento de datos en un dispositivo. Los operadores de radar tienen que someterse a un largo proceso de aprendizaje para poder interpretar los datos del radar.<\/p>\n<p>La mayor\u00eda de radares TTWS operan dentro de un rango de frecuencia de 1-10 GHz. La radiaci\u00f3n en este rango es perfecto para atravesar paredes de concreto, madera, pl\u00e1stico, cristal y otro tipo de paredes. Para demostrar la validez de esta afirmaci\u00f3n, podr\u00edas escanear tu casa u oficina que suele estar congestionada de redes Wi-Fi.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">Wi-Fi 'radar' can see through walls <a href=\"http:\/\/t.co\/TsNnyAK013\" target=\"_blank\" rel=\"noopener nofollow\">http:\/\/t.co\/TsNnyAK013<\/a><\/p>\n<p>\u2014 Unofficial \u2721MOSSAD\u2721 (@MossadNews) <a href=\"https:\/\/twitter.com\/MossadNews\/status\/342370913066577920?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener nofollow\">June 5, 2013<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>Cuanto m\u00e1s alta sea la frecuencia, m\u00e1s dif\u00edcil es que la radiaci\u00f3n atraviese las paredes. Sin embargo, las frecuencias m\u00e1s altas aumentan la precisi\u00f3n de los tama\u00f1os y la distancia de los objetos. Adem\u00e1s, algunos materiales absorben las ondas de radio de forma selectiva en un rango reducido. Por eso los esc\u00e1neres avanzados pueden cambiar las frecuencias sobre la marcha o utilizar la parte ancha del espectro del radio.<\/p>\n<p>Al trabajar con impulsos cortos, es posible evaluar las distancias de los objetos por el tiempo que tarda la onda en ir y venir. La detecci\u00f3n de movimiento est\u00e1 basada en el Efecto Doppler: una onda reflejada por un objeto en movimiento cambia ligeramente su frecuencia, permitiendo, por ejemplo, detectar el movimiento casi est\u00e1tico del pecho de una persona respirando.<\/p>\n<p>No cabe duda de que los dispositivos TTWS tienen muchas limitaciones. Su principal restricci\u00f3n est\u00e1 en que las ondas de radio no pueden atravesar el metal. Por lo tanto, es imposible detectar a una persona en el interior de un coche o en un edificio de aluminio. El agua tiene propiedades similares a las del metal: el concreto h\u00famedo y poroso es una forma de defensa muy eficaz.<\/p>\n<blockquote class=\"twitter-pullquote\"><p>Mi hogar ya no es mi Castillo: la #tecnolog\u00eda que permite ver a trav\u00e9s de las paredes #espionaje #seguridad<\/p><a href=\"https:\/\/twitter.com\/share?url=https%3A%2F%2Fkas.pr%2F5eCk&amp;text=Mi+hogar+ya+no+es+mi+Castillo%3A+la+%23tecnolog%C3%ADa+que+permite+ver+a+trav%C3%A9s+de+las+paredes+%23espionaje+%23seguridad\" class=\"btn btn-twhite\" data-lang=\"en\" data-count=\"0\" target=\"_blank\" rel=\"noopener nofollow\">Tweet<\/a><\/blockquote>\n<p>Generalmente, una capa gruesa de concreto o ladrillo debilita la se\u00f1al. Normalmente es imposible detectar algo si el grosor de las paredes que separan el radar y el objeto es superior a 12 pulgadas (unos 30 cent\u00edmetros).<\/p>\n<p>El alcance de detecci\u00f3n de la mayor\u00eda de los dispositivos es de 50-60 pies (sobre unos 15-20 metros), mientras que los dispositivos que tienen antenas m\u00e1s grandes y fuentes de alimentaci\u00f3n m\u00e1s potentes pueden atravesar unos 230 pies aproximadamente (unos 70 metros). No necesariamente tiene que ser una persona dentro de la casa, tambi\u00e9n puede ser un perro o una cortina que se mueve por el aire. La interpretaci\u00f3n de un objeto no es siempre precisa, en especial cuando el proceso de evaluaci\u00f3n se hace en un tiempo muy limitado. Una evaluaci\u00f3n est\u00e1ndar dura s\u00f3lo un minuto aproximadamente.<\/p>\n<p>La mayor\u00eda de radares son port\u00e1tiles. Un operador de radares tiene que presionarlo contra la pared del edificio inspeccionado para eliminar el temblor. En ocasiones, hay situaciones en las que es imposible acercarse a las paredes, por esto algunos modelos de radar est\u00e1n equipados con tr\u00edpodes o <a href=\"http:\/\/www.tialinx.com\/\" target=\"_blank\" rel=\"noopener nofollow\">se colocan sobre robots o drones<\/a>.<\/p>\n<p>Los radares TTWS menos complicados s\u00f3lo muestran si una persona est\u00e1 viva o en movimiento dentro del edificio. Los dispositivos m\u00e1s complejos detectan la distancia con el objeto y su direcci\u00f3n, y proporcionan informaci\u00f3n sobre la distribuci\u00f3n aproximada del edificio y muestran los objetos en dos o tres dimensiones.<\/p>\n<p>Las soluciones experimentales ya parecen ser prometedoras (por lo menos dentro de las condiciones del laboratorio). Por ejemplo, el sistema Wi-Fi de un radar m\u00f3vil colocado sobre un par de robots <a href=\"http:\/\/www.ece.ucsb.edu\/~ymostofi\/SeeThroughImaging.html\" target=\"_blank\" rel=\"noopener nofollow\">permite generar el plano<\/a> de una casa completamente desconocida con una precisi\u00f3n de 0,7 pulgadas (2 cent\u00edmetros) exactamente. Todav\u00eda es una ficci\u00f3n para la producci\u00f3n masiva.<\/p>\n<p><span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe class=\"youtube-player\" type=\"text\/html\" width=\"640\" height=\"390\" src=\"https:\/\/www.youtube.com\/embed\/iF1fY3bPAt0?version=3&amp;rel=1&amp;fs=1&amp;showsearch=0&amp;showinfo=1&amp;iv_load_policy=1&amp;wmode=transparent\" frameborder=\"0\" allowfullscreen=\"true\"><\/iframe><\/span><\/p>\n<p><strong>C\u00f3mo contrarrestarlo:<\/strong> La mejor defensa contra el espionaje de un TTWS es un edificio blindado. Si tu casa est\u00e1 reforzada con concreto por todos lados, no tendr\u00e1s que hacer nada. De lo contrario, el aluminio o el papel pintado metalizado tambi\u00e9n es bueno. Tambi\u00e9n puedes dejar tres perros en tu casa, ya que los radares todav\u00eda no detectan a m\u00e1s de tres objetivos al mismo tiempo.<\/p>\n<p><strong>Es un terahert (no tan) alarmante<\/strong><\/p>\n<p>Si sigues las noticias de ciencia, seguramente habr\u00e1s escuchado algo sobre los detectores de terahertz que pueden ver a trav\u00e9s de las paredes y detectar bombas a grandes distancias. Publicaciones de este tipo aparecen peri\u00f3dicamente en Internet a ra\u00edz de alg\u00fan comunicado de prensa de alg\u00fan laboratorio cient\u00edfico que anuncia por en\u00e9sima vez alg\u00fan \u00e9xito considerable sobre algo.<\/p>\n<p>De hecho, los radares de terahertz s\u00f3lo se utilizan para las inspecciones de pasajeros en los aeropuertos. Estos radares se volvieron famosos por su capacidad de escanear a las personas, lo que significa que proporcionan una imagen muy detallada del cuerpo humano que se esconde bajo la ropa.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">Five cyber spy technologies that cannot be stopped by going offline <a href=\"http:\/\/t.co\/OEXWHPGsuF\" target=\"_blank\" rel=\"noopener nofollow\">http:\/\/t.co\/OEXWHPGsuF<\/a>  <a href=\"https:\/\/twitter.com\/hashtag\/security?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener nofollow\">#security<\/a> <a href=\"http:\/\/t.co\/EA7a94uKed\" target=\"_blank\" rel=\"noopener nofollow\">pic.twitter.com\/EA7a94uKed<\/a><\/p>\n<p>\u2014 Kaspersky (@kaspersky) <a href=\"https:\/\/twitter.com\/kaspersky\/status\/611888675614494720?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener nofollow\">June 19, 2015<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>La mayor\u00eda de aplicaciones \u201cde terahertz\u201d (que cubren un rango de 300GHz-10THz) siguen siendo ciencia ficci\u00f3n. En realidad, hay una gran cantidad de <a href=\"http:\/\/spectrum.ieee.org\/aerospace\/military\/the-truth-about-terahertz\" target=\"_blank\" rel=\"noopener nofollow\">problemas sin resolver<\/a> como el desvanecimiento de la se\u00f1al para atravesar varias barreras a la construcci\u00f3n de emisores compactos de radiaci\u00f3n de alta potencia.<\/p>\n<p>Existen otros mitos como: las c\u00e1maras infrarrojas que ven a trav\u00e9s de las paredes. Al contrario de lo que muchos creen, los detectores t\u00e9rmicos no pueden hacer nada de eso. Incluso una capa de vidrio mate o madera contrachapada sigue siendo imposible de atravesar para un detector infrarrojo.<\/p>\n<p><strong>C\u00f3mo contrarrestarlo:<\/strong> Qu\u00edtate el casco de papel aluminio o p\u00f3ntelo. T\u00fa decides.<\/p>\n<p><strong>\u00bfQu\u00e9 tipo de voces escuchas?<\/strong><\/p>\n<p>Cualquiera que haya visto pel\u00edculas de esp\u00edas, por lo menos una vez, sabe que cualquier conversaci\u00f3n se puede escuchar desde lejos, incluso a trav\u00e9s de una ventana. El cristal vibra por el impacto de las ondas sonoras, y los movimientos se pueden leer con un l\u00e1ser. Como medida de defensa, se inventaron unos \u201cinterruptores\u201d baratos y efectivos que se pueden pegar en los cristales para generar ruido de forma aleatoria.<\/p>\n<p>Los esp\u00edas contempor\u00e1neos llevan una vida m\u00e1s f\u00e1cil. <a href=\"http:\/\/newsoffice.mit.edu\/2014\/algorithm-recovers-speech-from-vibrations-0804\" target=\"_blank\" rel=\"noopener nofollow\">Pueden recuperar<\/a> una conversaci\u00f3n analizando un v\u00eddeo sin sonido con s\u00f3lo una parte de la habitaci\u00f3n visible en c\u00e1mara. El principio general es el mismo: cualquier objeto que est\u00e9 sujeto a vibraciones puede actuar como membrana. \u00c9sta podr\u00eda ser una bolsa de papas, la superficie de un vaso de agua, o incluso las hojas de una planta de un ficus.<\/p>\n<p><span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe class=\"youtube-player\" type=\"text\/html\" width=\"640\" height=\"390\" src=\"https:\/\/www.youtube.com\/embed\/FKXOucXB4a8?version=3&amp;rel=1&amp;fs=1&amp;showsearch=0&amp;showinfo=1&amp;iv_load_policy=1&amp;wmode=transparent\" frameborder=\"0\" allowfullscreen=\"true\"><\/iframe><\/span><\/p>\n<p>Los interruptores est\u00e1ndar para las ventanas no impiden que los dispositivos capten el sonido. Aunque, para descifrar la conversaci\u00f3n, el video debe de estar grabado con una c\u00e1mara especial de alta velocidad que pueda grabar miles de fotogramas por segundo (el valor tiene que ser m\u00e1s alto que la frecuencia de voz).<\/p>\n<p>Sin embargo, las c\u00e1maras de alta velocidad se est\u00e1n introduciendo r\u00e1pidamente en nuestras vidas. Por ejemplo, muchos smartphones modernos pueden grabar videos con una alta frecuencia de fotogramas por segundo que sirve para extraer informaci\u00f3n valiosa. Por ejemplo, puede servir para identificar individualmente a los participantes de una conversaci\u00f3n.<\/p>\n<p>Espiar a trav\u00e9s de las ventanas no es un problema actual ya que los drones son cada vez m\u00e1s econ\u00f3micos y avanzados.<\/p>\n<p><strong>C\u00f3mo contrarrestarlo: <\/strong>Las cortinas o persianas pueden evitar el \u201cvideo-espionaje\u201d. Es importante que las cortinas no sirvan de membranas de sonido; as\u00ed que es mejor optar por algo m\u00e1s pesado, o ponerle los interruptores que mencionamos antes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Antiguamente, las tecnolog\u00edas que permit\u00edan ver a trav\u00e9s de las paredes s\u00f3lo estaban al alcance de los servicios gubernamentales. Hoy en d\u00eda, la situaci\u00f3n ha cambiado debido al avance tecnol\u00f3gico, seguido de la bajada de precios de este campo.<\/p>\n","protected":false},"author":521,"featured_media":5748,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5,2737],"tags":[484,2056,588],"class_list":["post-5747","post","type-post","status-publish","format-standard","has-post-thumbnail","category-tips","category-privacy","tag-espionaje","tag-tecnologias","tag-wi-fi"],"hreflang":[{"hreflang":"es-mx","url":"https:\/\/latam.kaspersky.com\/blog\/watching-through-walls\/5747\/"},{"hreflang":"en-ae","url":"https:\/\/me-en.kaspersky.com\/blog\/watching-through-walls\/4985\/"},{"hreflang":"en-us","url":"https:\/\/usa.kaspersky.com\/blog\/watching-through-walls\/5580\/"},{"hreflang":"en-gb","url":"https:\/\/www.kaspersky.co.uk\/blog\/watching-through-walls\/5960\/"},{"hreflang":"es","url":"https:\/\/www.kaspersky.es\/blog\/watching-through-walls\/6400\/"},{"hreflang":"it","url":"https:\/\/www.kaspersky.it\/blog\/watching-through-walls\/6292\/"},{"hreflang":"ru","url":"https:\/\/www.kaspersky.ru\/blog\/watching-through-walls\/8294\/"},{"hreflang":"x-default","url":"https:\/\/www.kaspersky.com\/blog\/watching-through-walls\/9254\/"},{"hreflang":"pt-br","url":"https:\/\/www.kaspersky.com.br\/blog\/watching-through-walls\/5504\/"},{"hreflang":"de","url":"https:\/\/www.kaspersky.de\/blog\/watching-through-walls\/5763\/"},{"hreflang":"ja","url":"https:\/\/blog.kaspersky.co.jp\/watching-through-walls\/8157\/"},{"hreflang":"ru-kz","url":"https:\/\/blog.kaspersky.kz\/watching-through-walls\/8294\/"},{"hreflang":"en-au","url":"https:\/\/www.kaspersky.com.au\/blog\/watching-through-walls\/9254\/"},{"hreflang":"en-za","url":"https:\/\/www.kaspersky.co.za\/blog\/watching-through-walls\/9254\/"}],"acf":[],"banners":"","maintag":{"url":"https:\/\/latam.kaspersky.com\/blog\/tag\/espionaje\/","name":"espionaje"},"_links":{"self":[{"href":"https:\/\/latam.kaspersky.com\/blog\/wp-json\/wp\/v2\/posts\/5747","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/latam.kaspersky.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/latam.kaspersky.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/latam.kaspersky.com\/blog\/wp-json\/wp\/v2\/users\/521"}],"replies":[{"embeddable":true,"href":"https:\/\/latam.kaspersky.com\/blog\/wp-json\/wp\/v2\/comments?post=5747"}],"version-history":[{"count":2,"href":"https:\/\/latam.kaspersky.com\/blog\/wp-json\/wp\/v2\/posts\/5747\/revisions"}],"predecessor-version":[{"id":16196,"href":"https:\/\/latam.kaspersky.com\/blog\/wp-json\/wp\/v2\/posts\/5747\/revisions\/16196"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/latam.kaspersky.com\/blog\/wp-json\/wp\/v2\/media\/5748"}],"wp:attachment":[{"href":"https:\/\/latam.kaspersky.com\/blog\/wp-json\/wp\/v2\/media?parent=5747"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/latam.kaspersky.com\/blog\/wp-json\/wp\/v2\/categories?post=5747"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/latam.kaspersky.com\/blog\/wp-json\/wp\/v2\/tags?post=5747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}