{"id":3613,"date":"2014-07-31T14:40:11","date_gmt":"2014-07-31T14:40:11","guid":{"rendered":"http:\/\/kasperskydaily.com\/mexico\/?p=3613"},"modified":"2020-02-26T09:15:12","modified_gmt":"2020-02-26T15:15:12","slug":"cada-iphone-esta-equipado-con-herramientas-para-espiar-a-su-dueno","status":"publish","type":"post","link":"https:\/\/latam.kaspersky.com\/blog\/cada-iphone-esta-equipado-con-herramientas-para-espiar-a-su-dueno\/3613\/","title":{"rendered":"\u00bfLos iPhones Est\u00e1n Equipados Con Herramientas Para Espiar a sus Due\u00f1os?"},"content":{"rendered":"<p>Una reciente <a href=\"http:\/\/www.zdziarski.com\/blog\/?p=3441\" target=\"_blank\" rel=\"noopener nofollow\">publicaci\u00f3n<\/a> de\u00a0Jonathan Zdziarski, reconocido investigador de Seguridad de iOS, revel\u00f3 la presencia de servicios de monitoreo que corren segundo plano en la plataforma de dispositivos m\u00f3viles de Apple. Las declaraciones de Zdziarski causaron un fuerte revuelo en la comunidad de investigadores de seguridad y desembocaron en un aluvi\u00f3n de art\u00edculos que, o bien, acusaban a Apple de trabajar para la NSA o se dedicaban a defender a ultranza a la compa\u00f1\u00eda de Cupertino, California.<\/p>\n<p><a href=\"https:\/\/threatpost.com\/researcher-identifies-hidden-data-acquisition-services-in-ios\/107335\" target=\"_blank\" rel=\"noopener nofollow\">La verdad acerca de esta problem\u00e1tica<\/a>, en realidad,\u00a0se encuentra en el medio de ambos extremos. Si bien algunas funciones, que de hecho existen y est\u00e1n activas por defecto en todos los dispositivos de iOS pueden ser utilizadas para conectarse con el dispositivo e interceptar su contenido (aun si est\u00e9 est\u00e1 protegido con diferentes medidas de seguridad), los potenciales tendr\u00edan que lidear con\u00a0varias limitaciones para poder llevar adelante\u00a0este proceso. Por lo cual, este problema no es una emergencia global que requiera una acci\u00f3n inmediata por parte de los usuarios.<\/p>\n<p>La existencia de estos servicios no implica, necesariamente, malas intenciones de parte de Apple. En efecto, la compa\u00f1\u00eda respondi\u00f3 a las preguntas de los periodistas y public\u00f3 un <a href=\"http:\/\/support.apple.com\/kb\/HT6331\" target=\"_blank\" rel=\"noopener nofollow\">comunicado<\/a> en el que describi\u00f3 cada servicio de diagn\u00f3stico, asegurando que esas herramientas son utilizadas s\u00f3lo para el soporte t\u00e9cnico y el desarrollo empresarial de iOS. No obstante, lo cierto es que los usos indebidos de estos servicios no puede ser desestimados, ya que, bajo ciertas circunstancias podr\u00edan utilizarse para el espionaje de los usuarios.<\/p>\n<p><strong>Posibles escenarios de ataque<\/strong><\/p>\n<p>En primer lugar, un atacante tendr\u00eda que poder conectar f\u00edsicamente el dispositivo a su computadora v\u00eda USB y, para esto, el iPhone\/iPad tendr\u00eda que\u00a0estar desbloqueado. En este punto, iOS trata de establecer una sincronizaci\u00f3n con la PC, que es una conexi\u00f3n confiable mediante la cual se habilitar\u00e1 la transmisi\u00f3n de datos. Una vez que se realizaron estos pasos, el conjunto de claves y certificados se almacenan en la PC y, reci\u00e9n entonces, podr\u00e1n utilizarse para comunicarse con el dispositivo a trav\u00e9s de una red inal\u00e1mbrica. Por otra parte, el atacante podr\u00eda tambi\u00e9n robar los certificados desde la PC del usuario con un malware, a fin de\u00a0sortear el paso de la conexi\u00f3n f\u00edsica.<\/p>\n<div class=\"pullquote\">El atacante podr\u00eda tambi\u00e9n robar los certificados desde la PC del usuario con un malware<\/div>\n<p>Aqu\u00ed es donde\u00a0el conjunto de servicios presentes en cada iPhone entra en juego. Estas herramientas son capaces de capturar todo el tr\u00e1fico de datos\u00a0en el dispositivo, filtrar fotos, mensajes, contactos y otros contenidos. Los servicios, adem\u00e1s, permanecen activos m\u00e1s all\u00e1 de cualquier medida de seguridad que posea el tel\u00e9fono. De esta forma, un hipot\u00e9tico atacante que pueda acceder a los certificados, podr\u00eda conectarse remotamente al dispositivo y monitorearlo (presumiblemente, utilizando la misma red Wi-Fi que el usuario, dado que el Zdziarski no pudo comprobar que los ataques puedan realizarse desde una red de operadores de celulares).<\/p>\n<p><strong>\u00bfEs un problema grave?<\/strong><\/p>\n<p>No. Un atacante tendr\u00eda que, o bien, conseguir el dispositivo desbloqueado del usuario o hackear su PC. Luego de esto, establecer una conexi\u00f3n con el iPhone. Esa combinaci\u00f3n de factores es posible cuando una agencia del gobierno apunta a una persona espec\u00edfica, pero para el \u201cmercado masivo\u201d, este hackeo es bastante complicado y poco redituable. Existe una importante excepci\u00f3n: las personas cercanas a la potencial v\u00edctima. Compa\u00f1eros de trabajo, familiares, etc. Ellos podr\u00edan querer utilizar estos servicios, aunque, por suerte, requieren de un determinado software de hackeo que no es nada f\u00e1cil de conseguir. No obstante, para asegurarte de que estar\u00e1s a salvo de cualquier riesgo, sigue nuestro consejo:<\/p>\n<p><strong>\u00bfQu\u00e9 hacer?<\/strong><\/p>\n<p>Para evitar intervenciones ilegales, nunca utilices los cargadores de otras personas (que podr\u00edan ser dispositivos de sincronizaci\u00f3n). Utiliza \u00fanicamente tu cargador de pared. Una buena opci\u00f3n es utilizar alg\u00fan protector USB.<\/p>\n<blockquote class=\"twitter-pullquote\"><p>Para evitar que esp\u00eden tu #iPhone, utiliza \u00fanicamente tu cargador de pared y nunca le des tu iPhone desbloqueado a un extra\u00f1o.<\/p><a href=\"https:\/\/twitter.com\/share?url=https%3A%2F%2Fkas.pr%2F9UhV&amp;text=Para+evitar+que+esp%C3%ADen+tu+%23iPhone%2C+utiliza+%C3%BAnicamente+tu+cargador+de+pared+y+nunca+le+des+tu+iPhone+desbloqueado+a+un+extra%C3%B1o.\" class=\"btn btn-twhite\" data-lang=\"en\" data-count=\"0\" target=\"_blank\" rel=\"noopener nofollow\">Tweet<\/a><\/blockquote>\n<p>Nunca le des tu iPhone desbloqueado a extra\u00f1os o, al menos, aseg\u00farate de que est\u00e1s atento a lo que hacen con tu tel\u00e9fono. Para evitar que te roben los certificados directamente de tu PC, utiliza una <a href=\"https:\/\/latam.kaspersky.com\/descargas\/versiones-de-prueba\/internet-security\" target=\"_blank\" rel=\"noopener\">soluci\u00f3n de seguridad s\u00f3lida y confiable en tu computadora<\/a>. Una vez que tu iPhone fue sincronizado con una computadora, el dispositivo queda asociado a esa maquina indefinidamente y, la \u00fanica forma de deshacerse de este v\u00ednculo, es realizar una restauraci\u00f3n de f\u00e1brica del dispositivo. Afortunadamente, una reciente mejora en los servicios de iCloud permiten realizar esta tarea de limpieza sin mayores esfuerzos. S\u00f3lo aseg\u00farate de que tus archivos tengan su debida copia de respaldo.<\/p>\n<p>\u00a0<\/p>\n<p style=\"text-align: right\">Traducido por: Guillermo Vidal Quinteiro<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una reciente publicaci\u00f3n de\u00a0Jonathan Zdziarski, reconocido investigador de Seguridad de iOS, revel\u00f3 la presencia de servicios de monitoreo que corren segundo plano en la plataforma de dispositivos m\u00f3viles de Apple.<\/p>\n","protected":false},"author":32,"featured_media":3614,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6],"tags":[1347,484,1346,27,29,34,1348,37],"class_list":["post-3613","post","type-post","status-publish","format-standard","has-post-thumbnail","category-news","tag-duenos","tag-espionaje","tag-herramientas-para-espiar","tag-ios","tag-iphone","tag-malware-2","tag-monitoreo","tag-privacidad"],"hreflang":[{"hreflang":"es-mx","url":"https:\/\/latam.kaspersky.com\/blog\/cada-iphone-esta-equipado-con-herramientas-para-espiar-a-su-dueno\/3613\/"}],"acf":[],"banners":"","maintag":{"url":"https:\/\/latam.kaspersky.com\/blog\/tag\/duenos\/","name":"due\u00f1os"},"_links":{"self":[{"href":"https:\/\/latam.kaspersky.com\/blog\/wp-json\/wp\/v2\/posts\/3613","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/latam.kaspersky.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/latam.kaspersky.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/latam.kaspersky.com\/blog\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/latam.kaspersky.com\/blog\/wp-json\/wp\/v2\/comments?post=3613"}],"version-history":[{"count":2,"href":"https:\/\/latam.kaspersky.com\/blog\/wp-json\/wp\/v2\/posts\/3613\/revisions"}],"predecessor-version":[{"id":17531,"href":"https:\/\/latam.kaspersky.com\/blog\/wp-json\/wp\/v2\/posts\/3613\/revisions\/17531"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/latam.kaspersky.com\/blog\/wp-json\/wp\/v2\/media\/3614"}],"wp:attachment":[{"href":"https:\/\/latam.kaspersky.com\/blog\/wp-json\/wp\/v2\/media?parent=3613"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/latam.kaspersky.com\/blog\/wp-json\/wp\/v2\/categories?post=3613"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/latam.kaspersky.com\/blog\/wp-json\/wp\/v2\/tags?post=3613"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}