{"id":22152,"date":"2021-06-18T09:30:02","date_gmt":"2021-06-18T15:30:02","guid":{"rendered":"https:\/\/latam.kaspersky.com\/blog\/?p=22152"},"modified":"2021-06-18T09:30:02","modified_gmt":"2021-06-18T15:30:02","slug":"mitad-de-empleados-rechaza-actualizaciones-con-apoyo-de-personal-ti","status":"publish","type":"post","link":"https:\/\/latam.kaspersky.com\/blog\/mitad-de-empleados-rechaza-actualizaciones-con-apoyo-de-personal-ti\/22152\/","title":{"rendered":"Mitad de empleados rechaza actualizaciones con apoyo de personal TI"},"content":{"rendered":"<p>El 19% de los empleados latinoamericanos ha tenido una disputa con su departamento de TI sobre la importancia de actualizar con frecuencia los programas en sus dispositivos corporativos. Sorprendentemente, el 48% de ellos ha logrado tener la autorizaci\u00f3n del propio personal de TI para rechazar la instalaci\u00f3n de un software o sistema operativo espec\u00edfico. Estas son algunas de las conclusiones de nuestra <a href=\"https:\/\/www.kaspersky.com\/blog\/device-updates-report\/\" target=\"_blank\" rel=\"noopener nofollow\">\u00a0campa\u00f1a titulada \u201cDolor de cabeza\u201d<\/a>, que estudia el comportamiento de los usuarios en cuanto a las actualizaciones de sus dispositivos.<\/p>\n<p>Adem\u00e1s de aportar nuevas funciones y resolver fallos del sistema, las actualizaciones desempe\u00f1an un importante papel en la seguridad de las empresas: la correcci\u00f3n de vulnerabilidades. Estas lagunas en los programas o sistemas operativos permiten a personas no autorizadas acceder a la red de la empresa o a los datos confidenciales de las organizaciones.<\/p>\n<p>En este contexto, es preocupante que los equipos de TI permitan a los empleados mantener sistemas sin actualizar. Al 19% de los encuestados en Latinoam\u00e9rica que dijo que se han quejado por tener que realizar las actualizaciones en sus equipos, se les hizo dos preguntas adicionales: si se les permit\u00eda saltarse las actualizaciones (el 48% dijo que s\u00ed) y si pod\u00edan elegir qu\u00e9 actualizaciones hacer y cu\u00e1les no (el 56% dijo que pod\u00eda elegir).<\/p>\n<p><strong>Claudio Martinelli, director general para Am\u00e9rica Latina y el Caribe en Kaspersky, <\/strong>explica que al permitir que existan versiones antiguas en los dispositivos corporativos, los equipos de TI crean eslabones d\u00e9biles en la seguridad de las organizaciones: \u201c<em>Es como tener una cadena con un eslab\u00f3n de cintillo de nylon para evitar reemplazar la cadena completa<\/em>\u201c, <strong>expresa el ejecutivo<\/strong>.<\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-22153 size-full\" src=\"https:\/\/media.kasperskydaily.com\/wp-content\/uploads\/sites\/87\/2021\/06\/18085109\/Capture-1.jpg\" alt=\"\" width=\"925\" height=\"691\"><em>\u201cPara quienes no lo recuerden, el brote de WannaCry, ransomware que se propag\u00f3 exponencialmente en 2017 y gener\u00f3 US$4,000 millones de d\u00f3lares en p\u00e9rdidas en 150 pa\u00edses, aprovech\u00f3 una vulnerabilidad, la cual ten\u00eda arreglo, pero que pocas empresas hab\u00edan instalado. Cuatro a\u00f1os despu\u00e9s, nuestro informe sobre ransomware ha revelado que esa misma amenaza sigue representando el 16% de las detecciones en 2020. La raz\u00f3n por la que WannaCry sigue siendo popular es porque las redes corporativas a\u00fan tienen un eslab\u00f3n vulnerable, similar a una cadena con un cintillo de nylon para reparar un quiebre, lo que les facilita la entrada a los cibercriminales\u201d,<\/em> explica <strong>Martinelli.<\/strong><\/p>\n<p>El directivo se\u00f1ala que la seguridad de alto nivel debe ser conformada por capas, d\u00f3nde cada pieza debe ser fuerte para que la protecci\u00f3n final sea s\u00f3lida.<\/p>\n<p>Para evitar vulnerabilidades en la red corporativa, recomendamos las siguientes acciones:<\/p>\n<ul>\n<li>Mantenga una formaci\u00f3n rutinaria de concientizaci\u00f3n en materia de seguridad para todos los empleados con el fin de garantizar que las mejores pr\u00e1cticas est\u00e9n siempre presentes, como la actualizaci\u00f3n de los programas en los dispositivos corporativos.<\/li>\n<li>Cree pol\u00edticas en su sistema de seguridad para forzar las actualizaciones en equipos corporativos si un empleado no lo hace dentro de un per\u00edodo determinado.<\/li>\n<li>Utilice una soluci\u00f3n de seguridad que cuente con tecnolog\u00edas de detecci\u00f3n de malware por comportamiento y prevenci\u00f3n de <em>exploits <\/em>como<a href=\"https:\/\/latam.kaspersky.com\/enterprise-security\/edr-security-software-solution\" target=\"_blank\" rel=\"noopener\"> Kaspersky Endpoint Detection and Response (EDR) Optimum<\/a>. Esta soluci\u00f3n tiene la capacidad de detectar y bloquear estafas que explotan vulnerabilidades desconocidas (de d\u00eda cero).<\/li>\n<li>Habilite la evaluaci\u00f3n de vulnerabilidades y la gesti\u00f3n de parches para automatizar este proceso. Esto liberar\u00e1 al departamento de TI para tareas m\u00e1s estrat\u00e9gicas.<\/li>\n<li>Para los sistemas heredados (<em>legacy<\/em>) y no soportados (como Windows 7), se recomienda que las organizaciones mantengan estos equipos en una red dedicada (y separada de la red principal) y apliquen medidas de protecci\u00f3n adicionales, como la creaci\u00f3n de una lista de procesos permitidos con las funciones que el equipo podr\u00e1 realizar. Cualquier otra tarea ser\u00e1 bloqueada por defecto (denegaci\u00f3n por defecto).<\/li>\n<\/ul>\n<p><strong>Acerca de la encuesta <\/strong><\/p>\n<p>En abril de 2021, Kaspersky y Savanta llevaron a cabo una encuesta en l\u00ednea entre 15,000 encuestados para explorar las tendencias de c\u00f3mo se comporta la gente al actualizar sus dispositivos. La muestra inclu\u00eda 1.000 encuestados de Francia, Alemania, Italia, Espa\u00f1a y el Reino Unido, y 500 encuestados de Argentina, Australia, Austria, Brasil, Chile, China, Colombia, EAU, India, M\u00e9xico, Per\u00fa, Portugal, Ruman\u00eda, Rusia, Turqu\u00eda, Sud\u00e1frica, Pa\u00edses Bajos y Estados Unidos. Todos los participantes utilizaban un ordenador, un tel\u00e9fono inteligente y\/o una tableta para ocuparse de asuntos personales o laborales, y el 76% de ellos estaban empleados.<\/p>\n<input type=\"hidden\" class=\"category_for_banner\" value=\"kesb-ransomware\">\n","protected":false},"excerpt":{"rendered":"<p>Te explicamos c\u00f3mo esta pr\u00e1ctica crea eslabones d\u00e9biles en la protecci\u00f3n de las empresas y comparte las medidas de seguridad que deben tomarse. <\/p>\n","protected":false},"author":2526,"featured_media":21783,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2795,3539,6,3540,2738],"tags":[2785,5193,874,590,94,318,4300,5194,2954],"class_list":["post-22152","post","type-post","status-publish","format-standard","has-post-thumbnail","category-business","category-enterprise","category-news","category-smb","category-technology","tag-actualizacion-de-software","tag-corporaciones","tag-empresas","tag-encuesta","tag-latinoamerica","tag-reporte","tag-seguridad-corporativa","tag-seguridad-empresarial","tag-wannacry"],"hreflang":[{"hreflang":"es-mx","url":"https:\/\/latam.kaspersky.com\/blog\/mitad-de-empleados-rechaza-actualizaciones-con-apoyo-de-personal-ti\/22152\/"}],"acf":[],"banners":"","maintag":{"url":"https:\/\/latam.kaspersky.com\/blog\/tag\/actualizacion-de-software\/","name":"actualizaci\u00f3n de software"},"_links":{"self":[{"href":"https:\/\/latam.kaspersky.com\/blog\/wp-json\/wp\/v2\/posts\/22152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/latam.kaspersky.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/latam.kaspersky.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/latam.kaspersky.com\/blog\/wp-json\/wp\/v2\/users\/2526"}],"replies":[{"embeddable":true,"href":"https:\/\/latam.kaspersky.com\/blog\/wp-json\/wp\/v2\/comments?post=22152"}],"version-history":[{"count":1,"href":"https:\/\/latam.kaspersky.com\/blog\/wp-json\/wp\/v2\/posts\/22152\/revisions"}],"predecessor-version":[{"id":22154,"href":"https:\/\/latam.kaspersky.com\/blog\/wp-json\/wp\/v2\/posts\/22152\/revisions\/22154"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/latam.kaspersky.com\/blog\/wp-json\/wp\/v2\/media\/21783"}],"wp:attachment":[{"href":"https:\/\/latam.kaspersky.com\/blog\/wp-json\/wp\/v2\/media?parent=22152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/latam.kaspersky.com\/blog\/wp-json\/wp\/v2\/categories?post=22152"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/latam.kaspersky.com\/blog\/wp-json\/wp\/v2\/tags?post=22152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}