{"id":21162,"date":"2021-03-02T14:08:01","date_gmt":"2021-03-02T20:08:01","guid":{"rendered":"https:\/\/latam.kaspersky.com\/blog\/?post_type=emagazine&#038;p=21162"},"modified":"2021-09-07T09:56:52","modified_gmt":"2021-09-07T15:56:52","slug":"threat-intelligence-trends","status":"publish","type":"emagazine","link":"https:\/\/latam.kaspersky.com\/blog\/secure-futures-magazine\/threat-intelligence-trends\/21162\/","title":{"rendered":"C\u00f3mo evolucion\u00f3 la inteligencia contra amenazas y a d\u00f3nde ir\u00e1 despu\u00e9s"},"content":{"rendered":"<p>La ciberseguridad siempre se ha enfocado en la inteligencia que impulsa las herramientas. Este es el tipo de inteligencia que se encarga de luchar contra las mentes que producen el malware.<\/p>\n<p>El epicentro de la batalla consiste en identificar y analizar las amenazas, es decir, el trabajo que realiza la inteligencia contra amenazas. Lo que permite llamarlo inteligencia contra amenazas, en vez de simplemente informaci\u00f3n sobre amenazas, es el an\u00e1lisis.<\/p>\n<blockquote><p>El an\u00e1lisis es como las etiquetas que se encuentran en las paredes de un museo, en las que se explica por qu\u00e9 es importante la obra de arte. Se trata de la inteligencia que combina el contexto con el objeto, d\u00e1ndole sentido a las cosas simples. Es el puente que conecta la informaci\u00f3n con la acci\u00f3n.<\/p>\n<\/blockquote>\n<p>Para comprender por qu\u00e9 la inteligencia contra amenazas ser\u00e1 tan importante para el futuro de la ciberseguridad, es necesario que visitemos el museo de su evoluci\u00f3n.<\/p>\n<h2>Alguna vez hubo tiempos m\u00e1s inofensivos: A principios de la d\u00e9cada de los 2000<\/h2>\n<p>Mulholland Drive estaba en los cines, Shaggy y Destiny\u2019s Child vend\u00edan CD por montones. El correo electr\u00f3nico era un servicio habitual en las empresas, pero no era tan com\u00fan su uso de manera personal. Cualquier persona que fuera lo suficientemente friki como para \u201cnavegar en la red\u201d por diversi\u00f3n, podr\u00eda visitar un cibercaf\u00e9 para usar un codiciado y futurista equipo de escritorio iMac. Una revoluci\u00f3n que volviera el hardware m\u00e1s atractivo, parec\u00eda una novedosa creaci\u00f3n que dotar\u00eda de vistosidad y funcionalidad al producto.<\/p>\n<p>Fue entonces cuando los precursores de la inteligencia contra amenazas comenzaron a aparecer. En primer lugar, hab\u00eda listas negras con direcciones IP y URL. El software de seguridad, como los Sistemas de administraci\u00f3n de la informaci\u00f3n,<a href=\"https:\/\/en.wikipedia.org\/wiki\/Security_information_and_event_management\" target=\"_blank\" rel=\"noopener nofollow\"> los eventos de seguridad (SIEM)<\/a> y los <a href=\"https:\/\/en.wikipedia.org\/wiki\/Next-generation_firewall\" target=\"_blank\" rel=\"noopener nofollow\">Firewall de \u00faltima generaci\u00f3n (NGFW)<\/a> utilizaban las listas negras para dar alertas e informes. Los investigadores de seguridad buscaban amenazas manualmente y enviaban actualizaciones diarias a los clientes.<\/p>\n<h2>El brillante y nuevo pasado digital: 2010<\/h2>\n<p>Fue el a\u00f1o en que el Monte Eyjafjallaj\u00f6kull de Islandia detuvo vuelos a lo largo de Europa con una nube de cenizas. Todo el mundo hablaba de Wikileaks y la primavera \u00e1rabe. Facebook y Twitter se hab\u00edan convertido en nombres muy conocidos, pero estaban bastante lejos de ser utilizados por los vendedores y sus marcas. La <a href=\"https:\/\/www.kaspersky.com\/blog\/secure-futures-magazine\/dark-web-monitoring\/29084\/\" target=\"_blank\" rel=\"noopener nofollow\">red oscura<\/a> y las actividades malignas estaban explotando, mostrando los l\u00edmites del software de seguridad de entonces. Este no estaba dise\u00f1ado para procesar el n\u00famero de <a href=\"https:\/\/encyclopedia.kaspersky.com\/glossary\/indicator-of-compromise-ioc\/\" target=\"_blank\" rel=\"noopener\">indicadores de compromiso<\/a> que eran lanzados como un diluvio de ranas. No pod\u00edan identificar ni procesar las tormentas de arena de dominios maliciosos, IP y otras amenazas.<\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-21165 size-full\" src=\"https:\/\/media.kasperskydaily.com\/wp-content\/uploads\/sites\/87\/2021\/03\/02140613\/threat-intelligence-trends-inline.png\" alt=\"\" width=\"1024\" height=\"768\"><\/p>\n<p>La industria de la ciberseguridad respondi\u00f3. El aprendizaje autom\u00e1tico y la inteligencia artificial (IA) podr\u00edan automatizar y correlacionar una nueva escala. Con millones de sensores, sus datos alimentaron oc\u00e9anos de informaci\u00f3n. Los procesaron y analizaron con herramientas para grandes bases de datos. Estos sistemas empezaron a utilizarse para realizar una detecci\u00f3n compleja que abarcara todas las <a href=\"https:\/\/encyclopedia.kaspersky.com\/glossary\/attack-surface\/\" target=\"_blank\" rel=\"noopener\">superficies de ataque.<\/a> Y la tecnolog\u00eda basada en las grandes bases de datos dio origen a la idea de la inteligencia contra amenazas.<\/p>\n<h2>Las m\u00e1quinas se encuentran con los humanos: 2015<\/h2>\n<p>Fue en el a\u00f1o de \u201cJe Suis Charlie\u201d, cuando muchos se pusieron del lado de los sat\u00edricos franceses contra el terrorismo. 195 pa\u00edses llegaron a un convenio sobre el Acuerdo de Par\u00eds, pero el color de un vestido dividi\u00f3 al mundo firmemente en dos campos.<\/p>\n<blockquote><p>La inteligencia contra amenazas evolucion\u00f3 nuevamente. Esa tecnolog\u00eda de las grandes bases de datos emit\u00eda demasiadas alertas falsas. La ciberseguridad necesitaba a sus humanos de vuelta.<\/p>\n<\/blockquote>\n<p>Los expertos en seguridad que supervisan la recopilaci\u00f3n de inteligencia pod\u00edan reducir los falsos positivos y observar mejor las amenazas y los m\u00e9todos de ataque espec\u00edficos en sus empresas. Esto signific\u00f3 una detecci\u00f3n y respuesta m\u00e1s r\u00e1pidas, y un cambio de enfoque en la b\u00fasqueda y priorizaci\u00f3n de vulnerabilidades.<\/p>\n<h2>El mundo que conocemos ahora<\/h2>\n<p>A partir del 2018, la industria de la inteligencia contra amenazas aumentaba. Aparecieron cientos de nuevas empresas que ofrec\u00edan servicios espec\u00edficos enfocados en la calidad de los datos. Su objetivo era dar lineamientos para tomar decisiones y acciones. Las empresas que compraban productos y servicios de inteligencia contra amenazas comenzaron a utilizarlos de manera m\u00e1s eficaz, por ejemplo, adaptando la recopilaci\u00f3n de sus datos a las necesidades de seguridad.<\/p>\n<p>Para el 2019 la industria hab\u00eda adoptado una comprensi\u00f3n compartida de lo que significa la inteligencia contra amenazas. Tengan paciencia, esta cadena tiene solo algunos eslabones. La inteligencia contra amenazas implica que hay varias fuentes que proporcionan datos relevantes y espec\u00edficos. Los datos deben convertirse en informaci\u00f3n que pueda utilizarse inmediatamente. Debe integrarse a las operaciones de seguridad de una empresa mediante un \u00fanico punto de entrada, y comunicarse sin problemas con sus controles de seguridad existentes. Su visi\u00f3n \u00fanica sobre las amenazas emergentes permitir\u00e1 que los equipos de seguridad prioricen las alertas, maximicen los recursos y tomen decisiones r\u00e1pidas.<\/p>\n<p>\u00bfY qu\u00e9 ocurrir\u00e1 a partir del 2020? El mercado sigue creciendo. Las investigaciones sugieren que la inteligencia contra amenazas podr\u00eda valer 13 mil millones de d\u00f3lares en el 2023. Empresas cada vez m\u00e1s peque\u00f1as est\u00e1n empezando a utilizar la inteligencia contra amenazas.<\/p>\n<p>Pero, en general, esta ser\u00e1 una nueva era de cooperaci\u00f3n. Para ser m\u00e1s completos, los proveedores de ciberseguridad ya est\u00e1n integrando sus productos y servicios con otros.<\/p>\n<blockquote><p>Compartir las pr\u00e1cticas recomendadas ser\u00e1 la nueva normalidad, lo cual generar\u00e1 mejores defensas contra el aumento de amenazas, como los ataques sin malware.<\/p>\n<\/blockquote>\n<p>La ciberseguridad pasar\u00e1 de ser reactiva a proactiva, a la vez que aumentar\u00e1 el papel de los equipos de seguridad en las empresas. Interactuar\u00e1n m\u00e1s en todos los niveles y con todos los grupos empresariales. Se har\u00e1n responsables de entregar una inteligencia contra amenazas proactiva que no solo proteger\u00e1, sino que identificar\u00e1 riesgos y configurar\u00e1 los objetivos empresariales. La inteligencia contra amenazas predecir\u00e1 y prevendr\u00e1 de forma eficaz los ataques en las primeras etapas y, tarde o temprano, sustentar\u00e1 todo el concepto de ciberseguridad proactiva y de riesgo en las empresas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Conozca los problemas que originaron el concepto de la inteligencia contra amenazas en la actualidad, y descubra cu\u00e1les son los desaf\u00edos a los que se enfrenta esta industria en constante desarrollo.<\/p>\n","protected":false},"author":2510,"featured_media":22654,"template":"","coauthors":[4810],"class_list":["post-21162","emagazine","type-emagazine","status-publish","has-post-thumbnail","emagazine-category-inteligencia-de-amenazas","emagazine-tag-amenazas","emagazine-tag-historia","emagazine-tag-ia","emagazine-tag-predicciones"],"hreflang":[{"hreflang":"es-mx","url":"https:\/\/latam.kaspersky.com\/blog\/secure-futures-magazine\/threat-intelligence-trends\/21162\/"},{"hreflang":"en-us","url":"https:\/\/usa.kaspersky.com\/blog\/secure-futures-magazine\/threat-intelligence-trends\/21687\/"},{"hreflang":"en-gb","url":"https:\/\/www.kaspersky.co.uk\/blog\/secure-futures-magazine\/threat-intelligence-trends\/20000\/"},{"hreflang":"x-default","url":"https:\/\/www.kaspersky.com\/blog\/secure-futures-magazine\/threat-intelligence-trends\/35109\/"},{"hreflang":"pt-br","url":"https:\/\/www.kaspersky.com.br\/blog\/secure-futures-magazine\/threat-intelligence-trends\/17022\/"}],"acf":[],"_links":{"self":[{"href":"https:\/\/latam.kaspersky.com\/blog\/wp-json\/wp\/v2\/emagazine\/21162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/latam.kaspersky.com\/blog\/wp-json\/wp\/v2\/emagazine"}],"about":[{"href":"https:\/\/latam.kaspersky.com\/blog\/wp-json\/wp\/v2\/types\/emagazine"}],"author":[{"embeddable":true,"href":"https:\/\/latam.kaspersky.com\/blog\/wp-json\/wp\/v2\/users\/2510"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/latam.kaspersky.com\/blog\/wp-json\/wp\/v2\/media\/22654"}],"wp:attachment":[{"href":"https:\/\/latam.kaspersky.com\/blog\/wp-json\/wp\/v2\/media?parent=21162"}],"wp:term":[{"taxonomy":"author","embeddable":true,"href":"https:\/\/latam.kaspersky.com\/blog\/wp-json\/wp\/v2\/coauthors?post=21162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}